{"id":7971,"date":"2023-09-21T11:17:50","date_gmt":"2023-09-21T09:17:50","guid":{"rendered":"https:\/\/www.beewhisper.com\/blog\/"},"modified":"2025-02-20T12:10:23","modified_gmt":"2025-02-20T10:10:23","slug":"blog","status":"publish","type":"page","link":"https:\/\/www.beewhisper.com\/it\/blog\/","title":{"rendered":"Blog"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; background_enable_image=&#8221;off&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; background_enable_color=&#8221;off&#8221; use_background_color_gradient=&#8221;off&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_row _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;IL VELENO DELLE API E GLI ESSERI UMANI&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;Verdana||||||||&#8221; title_text_align=&#8221;center&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; text_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_heading title=&#8221;Iliya Kanchev, Ph.D.&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h3&#8243; title_font=&#8221;Verdana||||||||&#8221; title_text_align=&#8221;center&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; max_height=&#8221;1000px&#8221; text_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Inter||||||||&#8221; text_letter_spacing=&#8221;-0.35px&#8221; background_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div class=\"title\">\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li>\n<ol>\n<ol>\n<li class=\"ql-indent-1\"><strong><span data-preserver-spaces=\"true\">Effetto del veleno delle api sull&#8217;uomo<\/span><\/strong><\/li>\n<li class=\"ql-indent-1\"><strong><span data-preserver-spaces=\"true\">L&#8217;effetto curativo del veleno d&#8217;api<\/span><\/strong><\/li>\n<\/ol>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><span data-preserver-spaces=\"true\"> <\/span><\/p>\n<h3><span data-preserver-spaces=\"true\"> <\/span><strong><span data-preserver-spaces=\"true\">Effetto del veleno delle api sull&#8217;uomo<\/span><\/strong><\/h3>\n<p><span data-preserver-spaces=\"true\">L&#8217;effetto del veleno delle api sull&#8217;uomo \u00e8 altamente individuale.<\/span><\/p>\n<p><span data-preserver-spaces=\"true\">L&#8217;effetto tipico \u00e8 il seguente:<\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Una reazione allergica si verifica nella maggior parte delle persone dopo una sola puntura. Questa reazione si verifica immediatamente o al massimo entro 4-5 ore dalla puntura. Nel caso di 200-300 punture simultanee, si osserva una reazione tossica nell&#8217;uomo. 500 punture simultanee possono portare alla morte dell&#8217;uomo a causa della paralisi del sistema respiratorio.   <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Per evitare o ridurre notevolmente le punture di api, i seguenti suggerimenti possono essere utili.<\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Puoi applicare olio di lavanda, olio di ricino e olio di menta piperita sulle parti del corpo scoperte o semplicemente strofinare foglie di menta piperita su tutto il corpo.<\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Le api sono piuttosto irritate dal forte odore di alcol, aglio, benzina, olio di paraffina e diesel. Non amano nemmeno i profumi con fragranze zuccherine. <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Non agitare mai le mani e muoviti il pi\u00f9 lentamente e con grazia possibile quando sei vicino alle api. Fai del tuo meglio per rimanere calmo, qualunque cosa accada. Le api possono percepire la nostra tensione, l&#8217;eccitazione e il nervosismo anche se non li manifestiamo visibilmente. Per questo \u00e8 importante mantenere la calma, qualunque cosa accada.   <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">In caso di puntura, \u00e8 molto utile fare quanto segue:<\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Per prima cosa, dobbiamo estrarre il pungiglione dal punto colpito. La cosa migliore \u00e8 usare una pinzetta. Poi, puoi applicare sul punto il cloruro di ammonio sciolto in alcol, il succo di cipolla, l&#8217;aglio dragoncello o semplicemente l&#8217;alcol puro. Questi mezzi distruggono in parte il veleno.   <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">L&#8217;ipersensibilit\u00e0 al veleno delle api si osserva nello 0,5-2% delle persone.<\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Quando lavori con il veleno delle api, devi utilizzare maschere protettive per la respirazione e occhiali protettivi.<\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Il pungiglione delle api \u00e8 un organo di autodifesa. Quando l&#8217;ape usa il suo pungiglione, il pi\u00f9 delle volte muore perch\u00e9 l&#8217;ape non riesce a tirarla fuori dal punto in cui \u00e8 stata punta. L&#8217;aspetto interessante \u00e8 che quando l&#8217;ape punge animali a sangue caldo, muore. Mentre quando l&#8217;ape punge gli insetti, non muore. Gli insetti muoiono quasi subito a causa del veleno delle api, mentre i topi vivono per circa 1-2 ore.    <\/span><\/p>\n<h3><strong><span data-preserver-spaces=\"true\">  L&#8217;effetto curativo del veleno d&#8217;api<\/span><\/strong><\/h3>\n<p><span data-preserver-spaces=\"true\">Il veleno d&#8217;api come medicinale \u00e8 stato utilizzato fin dall&#8217;antichit\u00e0. Un medicinale contenente veleno d&#8217;api e miele \u00e8 stato utilizzato in un passato remoto per il trattamento della calvizie e la stimolazione della crescita dei capelli. \u00c8 risaputo che il re russo Ivan il Terribile e il re svedese Carlo XII hanno utilizzato il veleno d&#8217;api come ingrediente per il trattamento della gotta.  <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Tuttavia, \u00e8 bene ricordare che quando viene utilizzato in modo improprio e non corretto come medicinale, pu\u00f2 causare danni considerevoli. Nessuno dovrebbe utilizzare il veleno d&#8217;api sul corpo umano senza le rispettive basi teoriche, una formazione pratica e un&#8217;adeguata sorveglianza clinica. Potrebbe essere pericoloso per la vita.  <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">I farmaci a base di veleno d&#8217;api agiscono sul corpo umano riducendo i dolori acuti e l&#8217;infiammazione nell&#8217;artrite reumatoide e nella radicolite. Sono utilizzati per il trattamento della sciatica, dell&#8217;infiammazione del nervo sciatico e di varie nevrosi; hanno un effetto tonico sul muscolo cardiaco, riducono la coagulazione del sangue e aumentano i livelli di emoglobina. <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">L&#8217;effetto curativo del veleno d&#8217;api. (5) <\/span><\/p>\n<ol>\n<li><strong><span data-preserver-spaces=\"true\">Sistema nervoso<\/span><\/strong><\/li>\n<\/ol>\n<ul>\n<ul>\n<li class=\"ql-indent-1\"><span data-preserver-spaces=\"true\">I<\/span><em><span data-preserver-spaces=\"true\">n piccole dosi ha un effetto stimolante, in grandi dosi ha un effetto confortante.<\/span><\/em><\/li>\n<li class=\"ql-indent-1\"><em><span data-preserver-spaces=\"true\">Effetto analgesico espresso<\/span><\/em><\/li>\n<li class=\"ql-indent-1\"><em><span data-preserver-spaces=\"true\">Effetto anticonvulsivo<\/span><\/em><\/li>\n<li class=\"ql-indent-1\"><em><span data-preserver-spaces=\"true\">Migliora l&#8217;umore, la memoria e il sonno<\/span><\/em><\/li>\n<li class=\"ql-indent-1\"><em><span data-preserver-spaces=\"true\">Riduce la dipendenza da alcol e nicotina<\/span><\/em><\/li>\n<li class=\"ql-indent-1\"><em><span data-preserver-spaces=\"true\">Migliora il flusso sanguigno nel cervello<\/span><\/em><\/li>\n<\/ul>\n<\/ul>\n<ol>\n<li><strong><span data-preserver-spaces=\"true\">Sistema cardiovascolare<\/span><\/strong><\/li>\n<\/ol>\n<ul>\n<ul>\n<li class=\"ql-indent-1\"><em><span data-preserver-spaces=\"true\">Effetto vasodilatatore; riduce la pressione sanguigna<\/span><\/em><\/li>\n<li class=\"ql-indent-1\"><em><span data-preserver-spaces=\"true\">Migliora la salute del cuore<\/span><\/em><\/li>\n<li class=\"ql-indent-1\"><em><span data-preserver-spaces=\"true\">Effetto anticoagulante<\/span><\/em><\/li>\n<li class=\"ql-indent-1\"><em><span data-preserver-spaces=\"true\">Effetto antiaggregante<\/span><\/em><\/li>\n<li class=\"ql-indent-1\"><em><span data-preserver-spaces=\"true\">Aumenta il volume del sangue circolante<\/span><\/em><\/li>\n<li class=\"ql-indent-1\"><em><span data-preserver-spaces=\"true\">Effetto antiaritmico<\/span><\/em><\/li>\n<li class=\"ql-indent-1\"><em><span data-preserver-spaces=\"true\">Effetto antianemico<\/span><\/em><\/li>\n<\/ul>\n<\/ul>\n<ol>\n<li><strong><span data-preserver-spaces=\"true\">Sistema respiratorio<\/span><\/strong><\/li>\n<\/ol>\n<ul>\n<ul>\n<li class=\"ql-indent-1\"><em><span data-preserver-spaces=\"true\">Dilata i bronchi<\/span><\/em><\/li>\n<li class=\"ql-indent-1\"><em><span data-preserver-spaces=\"true\">Effetto espettorante<\/span><\/em><\/li>\n<\/ul>\n<\/ul>\n<ol>\n<li><strong><span data-preserver-spaces=\"true\">Tratto gastrointestinale<\/span><\/strong><\/li>\n<\/ol>\n<ul>\n<ul>\n<li class=\"ql-indent-1\"><em><span data-preserver-spaces=\"true\">Stimola la peristalsi<\/span><\/em><\/li>\n<li class=\"ql-indent-1\"><em><span data-preserver-spaces=\"true\">Effetto antiulcera<\/span><\/em><\/li>\n<\/ul>\n<\/ul>\n<p><span data-preserver-spaces=\"true\">Il veleno d&#8217;api naturale essiccato viene utilizzato per la produzione di preparati farmaceutici contenenti veleno d&#8217;api. Esiste una speciale tecnologia per purificare il veleno d&#8217;api, finalizzata alla separazione dei componenti pi\u00f9 aggressivi che possono causare effetti collaterali, come allergie e intossicazioni. Il veleno d&#8217;api purificato ha un effetto notevolmente migliore sulla salute dell&#8217;organismo umano. Tuttavia, \u00e8 possibile che alcuni pazienti siano intolleranti al veleno d&#8217;api.   <\/span><\/p>\n<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_toggle title=&#8221;Bibliografia:&#8221; icon_color=&#8221;#000000&#8243; toggle_icon=&#8221;&#x47;||divi||400&#8243; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;30px&#8221; open_icon_color=&#8221;#000000&#8243; open_toggle_icon=&#8221;&#xe04b;||divi||400&#8243; open_use_icon_font_size=&#8221;on&#8221; open_icon_font_size=&#8221;30px&#8221; icon_font_size_tablet=&#8221;30px&#8221; icon_font_size_phone=&#8221;30px&#8221; icon_font_size_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ol>\n<li>\u0427\u0443\u0434\u0430\u043a\u043e\u0432 \u0412.\u0413. \u0422\u0435\u0445\u043d\u043e\u043b\u043e\u0433\u0438\u044f \u043f\u0440\u043e\u0434\u0443\u043a\u0442\u043e\u0432 \u043f\u0447\u0435\u043b\u043e\u0432\u043e\u0434\u0441\u0442\u0432\u0430. &#8211; \u041c.: \u041a\u043e\u043b\u043e\u0441, 1979. &#8211; 200 \u0441.<\/li>\n<li>\u0422\u0423 46 \u0420\u0421\u0424\u0421\u0420 67-72 &#8220;\u042f\u0434 \u043f\u0447\u0435\u043b\u0438\u043d\u044b\u0439 \u0441\u044b\u0440\u0435\u0446&#8221; \u0438 \u0424\u0430\u0440\u043c\u0430\u043a\u043e\u043f\u0435\u0439\u043d\u043e\u0439 \u0441\u0442\u0430\u0442\u044c\u0435\u0439 \u0424\u0421 42-2683-89.<\/li>\n<li>\u0425\u043e\u043c\u0443\u0442\u043e\u0432 \u0410.\u0415., \u041a\u0430\u043b\u0430\u0448\u043d\u0438\u043a\u043e\u0432\u0430 \u041b.\u041c. \u0424\u0438\u0437\u0438\u043e\u043b\u043e\u0433\u0438\u0447\u0435\u0441\u043a\u0438\u0435 \u0430\u0441\u043f\u0435\u043a\u0442\u044b \u043f\u043e\u043b\u0443\u0447\u0435\u043d\u0438\u044f \u043f\u0447\u0435\u043b\u0438\u043d\u043e\u0433\u043e \u044f\u0434\u0430 \/\/ \u0410\u043f\u0438\u0442\u0435\u0440\u0430\u043f\u0438\u044f \u0441\u0435\u0433\u043e\u0434\u043d\u044f. &#8211; \u0420\u044b\u0431\u043d\u043e\u0435, 1997. &#8211; \u0441. 18-20<\/li>\n<li>\u0420\u0443\u043a\u043e\u0432\u043e\u0434\u0441\u0442\u043e \u043f\u043e \u0430\u043f\u0438\u0442\u0435\u0440\u0430\u043f\u0438\u0438 (\u043b\u0435\u0447\u0435\u043d\u0438\u0435 \u043f\u0447\u0435\u043b\u0438\u043d\u044b\u043c \u044f\u0434\u043e\u043c, \u043c\u0451\u0434\u043e\u043c, \u043f\u0440\u043e\u043f\u043e\u043b\u0438\u0441\u043e\u043c, \u0446\u0432\u0435\u0442\u043e\u0447\u043d\u043e\u0439 \u043f\u044b\u043b\u044c\u0446\u043e\u0439 \u0438 \u0434\u0440\u0443\u0433\u0438\u043c\u0438 \u043f\u0440\u043e\u0434\u0443\u043a\u0442\u0430\u043c\u0438 \u043f\u0447\u0435\u043b\u043e\u0432\u043e\u0434\u0441\u0442\u0432\u0430) \u0434\u043b\u044f \u0432\u0440\u0430\u0447\u0435\u0439, \u0441\u0442\u0443\u0434\u0435\u043d\u0442\u043e\u0432 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0441\u043a\u0438\u0445 \u0432\u0443\u0437\u043e\u0432 \u0438 \u043f\u0447\u0435\u043b\u043e\u0432\u043e\u0434\u043e\u0432 \/ \u042d. \u0410. \u041b\u0443\u0434\u044f\u043d\u0441\u043a\u0438\u0439. &#8211; \u0412\u043e\u043b\u043e\u0433\u0434\u0430 : [\u041f\u0424 &#8220;\u041f\u043e\u043b\u0438\u0433\u0440\u0430\u0444\u0438\u0441\u0442&#8221;], 1994. &#8211; 462 \u0441.    <\/li>\n<li>\u0410\u043f\u0438\u0442\u0435\u0440\u0430\u043f\u0438\u044f. \/ \u0425\u0438\u0441\u043c\u0430\u0442\u0443\u043b\u043b\u0438\u043d\u0430 \u041d.3. &#8211; \u041f\u0435\u0440\u043c\u044c: \u041c\u043e\u0431\u0438\u043b\u0435, 2005. &#8211; 296 \u0441.   <\/li>\n<li>\u0410\u043f\u0438\u0442\u0435\u0440\u0430\u043f\u0438\u044f: \u043f\u0440\u043e\u0434\u0443\u043a\u0442\u044b \u043f\u0447\u0435\u043b\u043e\u0432\u043e\u0434\u0441\u0442\u0432\u0430 \u0432 \u043c\u0438\u0440\u0435 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u044b. \/ \u041e\u043c\u0430\u0440\u043e\u0432 \u0428.\u041c. &#8211; \u0420\u043e\u0441\u0442\u043e\u0432 \u043d\/\u0414 : \u0424\u0435\u043d\u0438\u043a\u0441, 2009. &#8211; 351 \u0441.<\/li>\n<li>\u0413\u0438\u043d\u0438\u044f\u0442\u0443\u043b\u043b\u0438\u043d \u041d.\u0413., \u0418\u043b\u044c\u0431\u0443\u043b\u044c\u0434\u0438\u043d \u042e.\u0424. \u0412\u043b\u0438\u044f\u043d\u0438\u0435 \u043e\u0442\u0434\u0435\u043b\u044c\u043d\u044b\u0445 \u0444\u0430\u043a\u0442\u043e\u0440\u043e\u0432 \u043d\u0430 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u043e \u043f\u0447\u0435\u043b\u0438\u043d\u043e\u0433\u043e \u044f\u0434\u0430 \/\/ \u0410\u043f\u0438\u0442\u0435\u0440\u0430\u043f\u0438\u044f \u0441\u0435\u0433\u043e\u0434\u043d\u044f. &#8211; \u0420\u044b\u0431\u043d\u043e\u0435, 1993.<\/li>\n<li>\u041c\u0443\u0441\u0430\u0435\u0432 \u0424.\u0413. \u0411\u0438\u043e\u043b\u043e\u0433\u0438\u0447\u0435\u0441\u043a\u043e\u0435 \u043e\u0431\u043e\u0441\u043d\u043e\u0432\u0430\u043d\u0438\u0435 \u043f\u0440\u0438\u0435\u043c\u043e\u0432 \u043f\u043e\u043b\u0443\u0447\u0435\u043d\u0438\u044f \u044f\u0434\u0430 \u043e\u0442 \u043c\u0435\u0434\u043e\u043d\u043e\u0441\u043d\u044b\u0445 \u043f\u0447\u0435\u043b: \u0410\u0432\u0442\u043e\u0440\u0435\u0444. \u0434\u0438\u0441. \u043a\u0430\u043d\u0434. \u0431\u0438\u043e\u043b. \u043d-\u043a. &#8211; \u0411\u0430\u043a\u0443, 1982. &#8211; 17 \u0441.<\/li>\n<li>\u041a\u0440\u0438\u0432\u0446\u043e\u0432 \u041d.\u0418., \u041b\u0435\u0431\u0435\u0434\u0435\u0432 \u0412.\u0418. \u041f\u043e\u043b\u0443\u0447\u0435\u043d\u0438\u0435 \u0438\u0441\u043f\u043e\u043b\u044c\u0437\u043e\u0432\u0430\u043d\u0438\u0435 \u043f\u0440\u043e\u0434\u0443\u043a\u0442\u043e\u0432 \u043f\u0447\u0435\u043b\u043e\u0432\u043e\u0434\u0441\u0442\u0432\u0430. &#8211; \u041c.: \u041d\u0438\u0432\u0430 \u0420\u043e\u0441\u0441\u0438\u0438, 1993. &#8211; 285 \u0441<\/li>\n<li>\u041d\u041e\u0412\u041e\u0421\u0418\u0411\u0418\u0420\u0421\u041a\u0418\u0419 \u0413\u041e\u0421\u0423\u0414\u0410\u0420\u0421\u0422\u0412\u0415\u041d\u041d\u042b\u0419 \u0410\u0413\u0420\u0410\u0420\u041d\u042b\u0419 \u0423\u041d\u0418\u0412\u0415\u0420\u0421\u0418\u0422\u0415\u0422\u0418\u0422\u0418\u041d\u041d\u0418\u0422\u0423 \u0417\u0410\u041e\u0427\u041d\u0413 \u041e\u041e\u0411\u0420\u0410\u0417\u041e\u0412\u0410\u041d\u0418\u042f \u0418 \u041f\u041e\u0412\u042b\u0428\u0415\u041d\u0418\u042f \u041a\u0412\u0410\u041b\u0418\u0424\u0418\u041a\u0410\u0426\u0418 &#8220;\u0422\u0415\u0425\u041d\u041e\u041b\u0413\u0418\u042f \u041f\u0420\u0418\u0417\u0412\u041e\u0414\u0421\u0422\u0412\u0410 \u0411\u0418\u041e\u041b\u0413\u0418\u0418\u0427\u0415\u0421\u041a\u0418 \u0410\u041a\u0422\u0418\u0412\u0425 \u041f\u0420\u041e\u0414\u0423\u041a\u0412 \u041f\u0427\u0415\u041b\u0412\u041e\u0414\u0421\u0422\u0410&#8221; &#8211; \u0423\u0447\u0435\u0431\u043d\u043e\u0435 \u043f\u043e\u0441\u043e\u0431\u0438\u0435<\/li>\n<\/ol>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_divider _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Veleno d&#039;ape&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;Verdana||||||||&#8221; title_text_align=&#8221;center&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; text_shadow_style=&#8221;preset1&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;1px|auto||auto||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Iliya Kanchev, Ph.D.&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h3&#8243; title_font=&#8221;Verdana||||||||&#8221; title_text_align=&#8221;center&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; max_height=&#8221;1000px&#8221; text_shadow_style=&#8221;preset1&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Inter||||||||&#8221; background_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div class=\"title\">\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li style=\"text-align: left;\">\n<ol>\n<ol>\n<li class=\"ql-indent-1\"><strong><span data-preserver-spaces=\"true\">Produzione e componenti<\/span><\/strong><\/li>\n<li class=\"ql-indent-1\"><strong><span data-preserver-spaces=\"true\">Raccogliere il veleno delle api<\/span><\/strong><\/li>\n<li class=\"ql-indent-1\"><strong><span data-preserver-spaces=\"true\">Immagazzinamento<\/span><\/strong><\/li>\n<\/ol>\n<\/ol>\n<h3><span data-preserver-spaces=\"true\">Produzione e componenti<\/span><\/h3>\n<p><span data-preserver-spaces=\"true\">Il veleno delle api \u00e8 un liquido incolore addensato dall&#8217;odore pungente e dal sapore amaro-caldo. (10) Viene prodotto al momento della puntura quando la secrezione della ghiandola velenifera piccola entra in contatto con quella della ghiandola velenifera grande. La lunghezza delle ghiandole velenifere dipende dalla razza dell&#8217;ape. La razza determina anche l&#8217;et\u00e0 in cui l&#8217;ape inizia a produrre veleno.    <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Di solito, le api operaie possono iniziare a produrre veleno dopo 1 settimana di et\u00e0. Le api sono pi\u00f9 attive tra le 2 e le 3 settimane di et\u00e0. Il veleno delle api \u00e8 composto dai seguenti elementi (1) :  <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">  melittina 40-50%  <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">  apamina 3,4-5,1 %  <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">  altri peptidi fino al 16%  <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">  ialuronidasi 20%  <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">  Fosfolipasi \u0410 14%  <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">  aminoacidi fino all&#8217;1%  <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">  istamina 0,5% -1,7%  <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">  grassi e steroli fino al 5%  <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">  glucosio 0,5%  <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">  fruttosio 0,9%  <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">  acido organico 0,04% &#8211; 0,14%  <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">  altri componenti 4% -10%  <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">  <\/span><\/p>\n<h3><span data-preserver-spaces=\"true\">Collezionare il veleno delle api<\/span><\/h3>\n<p><span data-preserver-spaces=\"true\">Il veleno pu\u00f2 essere raccolto senza danneggiare le api semplicemente utilizzando la secrezione delle ghiandole velenifere piccole e grandi. Raccogliere regolarmente il veleno stimolando le api a pungere pu\u00f2 portare le api a produrre il doppio del veleno che avrebbero prodotto normalmente. Durante la sua vita, un&#8217;ape pu\u00f2 produrre fino a 0,3 mg di veleno. I metodi di raccolta del veleno si basano sul principio dell&#8217;introduzione di un irritante che fa pungere l&#8217;ape. Attualmente, il metodo pi\u00f9 comune per raccogliere il veleno \u00e8 l&#8217;utilizzo di una carica elettrica che stimola l&#8217;ape a pungere. In passato si utilizzava una carica elettrica, ma non era possibile controllarne l&#8217;entit\u00e0 e quindi preservare il benessere delle api. Oggi, i dispositivi pi\u00f9 avanzati per la stimolazione tramite cariche elettriche, come il Collector-beeWhisper, hanno un microprocessore che controlla la carica elettrica in modo da non danneggiare le api e mantenerle in vita. Il tasso di mortalit\u00e0 delle api \u00e8 stato ridotto a zero.       <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Il veleno delle api pu\u00f2 essere raccolto all&#8217;interno o all&#8217;esterno dell&#8217;alveare. Per evitare di stressare le api e preservare il benessere della colonia di api e la sua capacit\u00e0 di produrre miele e altri prodotti apistici, \u00e8 necessario utilizzare il metodo di raccolta del veleno all&#8217;esterno dell&#8217;alveare. Il dispositivo elettronico a microprocessore Bee Venom Collector &#8211; BVC, pu\u00f2 essere utilizzato all&#8217;esterno dell&#8217;alveare. Tuttavia, alcuni apicoltori scelgono di rimuovere il tetto dell&#8217;arnia e di collocare il dispositivo elettronico sopra il favo. Questa \u00e8 ancora l&#8217;opzione migliore rispetto all&#8217;inserimento del dispositivo all&#8217;interno dell&#8217;arnia al posto del favo. Se il raccoglitore di veleno viene posizionato tra i favi, le api subiranno uno shock. Le render\u00e0 iperattive e le porter\u00e0 a raggrupparsi intorno al dispositivo, aumentando notevolmente la temperatura dell&#8217;alveare. Nelle calde giornate estive, questo pu\u00f2 facilmente portare a colpi di calore e alla morte delle api.       <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Quando utilizziamo il Collettore &#8211; BVC, il veleno si asciuga sul pannello di vetro mentre viene ancora raccolto. Nella maggior parte dei casi, quando l&#8217;aria esterna \u00e8 secca, non \u00e8 necessario posizionare il raccoglitore sotto un&#8217;ombra e aspettare che il veleno si asciughi prima di raschiarlo dal pannello di vetro. Se l&#8217;umidit\u00e0 dell&#8217;aria \u00e8 superiore al 70%, i pannelli di vetro con il veleno devono essere messi all&#8217;ombra per 20-30 minuti affinch\u00e9 il veleno si asciughi. Una volta asciutto, il veleno pu\u00f2 essere facilmente rimosso con lo speciale raschietto incluso nel kit.   <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Durante il processo di essiccazione, la perdita di peso del veleno non deve essere superiore al 12%. La parte insolubile in acqua non deve superare il 13%. (2) I pannelli di vetro devono essere sterilizzati con il 70-90% di alcol etilico.  <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Quando l&#8217;umidit\u00e0 dell&#8217;aria \u00e8 troppo alta, ad esempio dopo la pioggia o quando fuori c&#8217;\u00e8 la nebbia, non \u00e8 consigliabile utilizzare una carica elettrica per stimolare le api. Quando l&#8217;aria \u00e8 umida, le api diventano migliori conduttori di elettricit\u00e0 e quindi una carica elettrica pu\u00f2 danneggiarle facilmente. Il raccoglitore &#8211; BVC,    <\/span><a target=\"_blank\" href=\"https:\/\/www.beewhisper.com\/it\/\" class=\"editor-rtfLink\" rel=\"noopener\"><span data-preserver-spaces=\"true\">www.beewhisper.com<\/span><\/a><span data-preserver-spaces=\"true\">Il Collector &#8211; BVC rileva il livello di umidit\u00e0 dell&#8217;aria e regola automaticamente l&#8217;entit\u00e0 della carica elettrica o la sospende fino a quando non \u00e8 sicuro riprenderla. Il Collettore &#8211; BVC \u00e8 dotato di indicatori LED per l&#8217;umidit\u00e0. In questo modo, il Collettore di veleno d&#8217;api &#8211; BVC,    <\/span><a target=\"_blank\" href=\"https:\/\/www.beewhisper.com\/it\/\" class=\"editor-rtfLink\" rel=\"noopener\"><span data-preserver-spaces=\"true\">www.beewhisper.com<\/span><\/a><span data-preserver-spaces=\"true\">si prende cura del benessere della colonia di api.<\/span><\/p>\n<h3><span data-preserver-spaces=\"true\">Immagazzinamento<\/span><\/h3>\n<p><span data-preserver-spaces=\"true\">Il veleno delle api [(5),(6)] \u00e8 solubile in acqua e oli vegetali. Pu\u00f2 essere disintegrato da ossidanti, acidi concentrati, alcali e luce solare diretta. Quando viene aerato, il veleno si asciuga rapidamente e si trasforma in cristalli amorfi. Durante il processo di essiccazione, oltre al vapore acqueo, il veleno delle api emette anche frazioni volatili di veleno. Si tratta di 12 sostanze diverse. Per questo motivo il veleno d&#8217;api deve essere conservato in contenitori ermetici. Il veleno ben essiccato, conservato in un contenitore ermetico di vetro colorato, pu\u00f2 conservare le sue qualit\u00e0 per un paio d&#8217;anni anche a temperatura ambiente.      <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Il veleno delle api \u00e8 solubile negli acidi, nella soluzione salina e nell&#8217;acqua, tuttavia la sua attivit\u00e0 biologica si riduce in un paio d&#8217;ore.<\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Il veleno non \u00e8 facilmente solubile in alcol, ma pu\u00f2 formare emulsioni negli oli.<\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Il veleno non \u00e8 influenzato dalla temperatura: conserva le sue qualit\u00e0 sia in caso di congelamento che di temperature fino a 115C, equivalenti a 239F.<\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Il veleno d&#8217;api ben essiccato deve essere tenuto lontano dalla luce diretta del sole o da spazi umidi.<\/span><\/p>\n<p class=\"ql-indent-1\"><span data-preserver-spaces=\"true\">Il veleno d&#8217;api pu\u00f2 conservare le sue qualit\u00e0 per 7-8 anni se viene conservato in bottiglie o barattoli di vetro colorato sigillati con paraffina. Queste informazioni sono di primaria importanza per la raccolta e la conservazione del veleno d&#8217;api e dei farmaci che lo contengono. <\/span><\/p>\n<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_toggle title=&#8221;Bibliografia:&#8221; icon_color=&#8221;#000000&#8243; toggle_icon=&#8221;&#x47;||divi||400&#8243; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;30px&#8221; open_icon_color=&#8221;#000000&#8243; open_toggle_icon=&#8221;&#xe04b;||divi||400&#8243; open_use_icon_font_size=&#8221;on&#8221; open_icon_font_size=&#8221;30px&#8221; icon_font_size_tablet=&#8221;30px&#8221; icon_font_size_phone=&#8221;30px&#8221; icon_font_size_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ol>\n<li>\u0427\u0443\u0434\u0430\u043a\u043e\u0432 \u0412.\u0413. \u0422\u0435\u0445\u043d\u043e\u043b\u043e\u0433\u0438\u044f \u043f\u0440\u043e\u0434\u0443\u043a\u0442\u043e\u0432 \u043f\u0447\u0435\u043b\u043e\u0432\u043e\u0434\u0441\u0442\u0432\u0430. &#8211; \u041c.: \u041a\u043e\u043b\u043e\u0441, 1979. &#8211; 200 \u0441.<\/li>\n<li>\u0422\u0423 46 \u0420\u0421\u0424\u0421\u0420 67-72 &#8220;\u042f\u0434 \u043f\u0447\u0435\u043b\u0438\u043d\u044b\u0439 \u0441\u044b\u0440\u0435\u0446&#8221; \u0438 \u0424\u0430\u0440\u043c\u0430\u043a\u043e\u043f\u0435\u0439\u043d\u043e\u0439 \u0441\u0442\u0430\u0442\u044c\u0435\u0439 \u0424\u0421 42-2683-89.<\/li>\n<li>\u0425\u043e\u043c\u0443\u0442\u043e\u0432 \u0410.\u0415., \u041a\u0430\u043b\u0430\u0448\u043d\u0438\u043a\u043e\u0432\u0430 \u041b.\u041c. \u0424\u0438\u0437\u0438\u043e\u043b\u043e\u0433\u0438\u0447\u0435\u0441\u043a\u0438\u0435 \u0430\u0441\u043f\u0435\u043a\u0442\u044b \u043f\u043e\u043b\u0443\u0447\u0435\u043d\u0438\u044f \u043f\u0447\u0435\u043b\u0438\u043d\u043e\u0433\u043e \u044f\u0434\u0430 \/\/ \u0410\u043f\u0438\u0442\u0435\u0440\u0430\u043f\u0438\u044f \u0441\u0435\u0433\u043e\u0434\u043d\u044f. &#8211; \u0420\u044b\u0431\u043d\u043e\u0435, 1997. &#8211; \u0441. 18-20<\/li>\n<li>\u0420\u0443\u043a\u043e\u0432\u043e\u0434\u0441\u0442\u043e \u043f\u043e \u0430\u043f\u0438\u0442\u0435\u0440\u0430\u043f\u0438\u0438 (\u043b\u0435\u0447\u0435\u043d\u0438\u0435 \u043f\u0447\u0435\u043b\u0438\u043d\u044b\u043c \u044f\u0434\u043e\u043c, \u043c\u0451\u0434\u043e\u043c, \u043f\u0440\u043e\u043f\u043e\u043b\u0438\u0441\u043e\u043c, \u0446\u0432\u0435\u0442\u043e\u0447\u043d\u043e\u0439 \u043f\u044b\u043b\u044c\u0446\u043e\u0439 \u0438 \u0434\u0440\u0443\u0433\u0438\u043c\u0438 \u043f\u0440\u043e\u0434\u0443\u043a\u0442\u0430\u043c\u0438 \u043f\u0447\u0435\u043b\u043e\u0432\u043e\u0434\u0441\u0442\u0432\u0430) \u0434\u043b\u044f \u0432\u0440\u0430\u0447\u0435\u0439, \u0441\u0442\u0443\u0434\u0435\u043d\u0442\u043e\u0432 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u0441\u043a\u0438\u0445 \u0432\u0443\u0437\u043e\u0432 \u0438 \u043f\u0447\u0435\u043b\u043e\u0432\u043e\u0434\u043e\u0432 \/ \u042d. \u0410. \u041b\u0443\u0434\u044f\u043d\u0441\u043a\u0438\u0439. &#8211; \u0412\u043e\u043b\u043e\u0433\u0434\u0430 : [\u041f\u0424 &#8220;\u041f\u043e\u043b\u0438\u0433\u0440\u0430\u0444\u0438\u0441\u0442&#8221;], 1994. &#8211; 462 \u0441.    <\/li>\n<li>\u0410\u043f\u0438\u0442\u0435\u0440\u0430\u043f\u0438\u044f. \/ \u0425\u0438\u0441\u043c\u0430\u0442\u0443\u043b\u043b\u0438\u043d\u0430 \u041d.3. &#8211; \u041f\u0435\u0440\u043c\u044c: \u041c\u043e\u0431\u0438\u043b\u0435, 2005. &#8211; 296 \u0441.   <\/li>\n<li>\u0410\u043f\u0438\u0442\u0435\u0440\u0430\u043f\u0438\u044f: \u043f\u0440\u043e\u0434\u0443\u043a\u0442\u044b \u043f\u0447\u0435\u043b\u043e\u0432\u043e\u0434\u0441\u0442\u0432\u0430 \u0432 \u043c\u0438\u0440\u0435 \u043c\u0435\u0434\u0438\u0446\u0438\u043d\u044b. \/ \u041e\u043c\u0430\u0440\u043e\u0432 \u0428.\u041c. &#8211; \u0420\u043e\u0441\u0442\u043e\u0432 \u043d\/\u0414 : \u0424\u0435\u043d\u0438\u043a\u0441, 2009. &#8211; 351 \u0441.<\/li>\n<li>\u0413\u0438\u043d\u0438\u044f\u0442\u0443\u043b\u043b\u0438\u043d \u041d.\u0413., \u0418\u043b\u044c\u0431\u0443\u043b\u044c\u0434\u0438\u043d \u042e.\u0424. \u0412\u043b\u0438\u044f\u043d\u0438\u0435 \u043e\u0442\u0434\u0435\u043b\u044c\u043d\u044b\u0445 \u0444\u0430\u043a\u0442\u043e\u0440\u043e\u0432 \u043d\u0430 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u043e \u043f\u0447\u0435\u043b\u0438\u043d\u043e\u0433\u043e \u044f\u0434\u0430 \/\/ \u0410\u043f\u0438\u0442\u0435\u0440\u0430\u043f\u0438\u044f \u0441\u0435\u0433\u043e\u0434\u043d\u044f. &#8211; \u0420\u044b\u0431\u043d\u043e\u0435, 1993.<\/li>\n<li>\u041c\u0443\u0441\u0430\u0435\u0432 \u0424.\u0413. \u0411\u0438\u043e\u043b\u043e\u0433\u0438\u0447\u0435\u0441\u043a\u043e\u0435 \u043e\u0431\u043e\u0441\u043d\u043e\u0432\u0430\u043d\u0438\u0435 \u043f\u0440\u0438\u0435\u043c\u043e\u0432 \u043f\u043e\u043b\u0443\u0447\u0435\u043d\u0438\u044f \u044f\u0434\u0430 \u043e\u0442 \u043c\u0435\u0434\u043e\u043d\u043e\u0441\u043d\u044b\u0445 \u043f\u0447\u0435\u043b: \u0410\u0432\u0442\u043e\u0440\u0435\u0444. \u0434\u0438\u0441. \u043a\u0430\u043d\u0434. \u0431\u0438\u043e\u043b. \u043d-\u043a. &#8211; \u0411\u0430\u043a\u0443, 1982. &#8211; 17 \u0441.<\/li>\n<li>\u041a\u0440\u0438\u0432\u0446\u043e\u0432 \u041d.\u0418., \u041b\u0435\u0431\u0435\u0434\u0435\u0432 \u0412.\u0418. \u041f\u043e\u043b\u0443\u0447\u0435\u043d\u0438\u0435 \u0438\u0441\u043f\u043e\u043b\u044c\u0437\u043e\u0432\u0430\u043d\u0438\u0435 \u043f\u0440\u043e\u0434\u0443\u043a\u0442\u043e\u0432 \u043f\u0447\u0435\u043b\u043e\u0432\u043e\u0434\u0441\u0442\u0432\u0430. &#8211; \u041c.: \u041d\u0438\u0432\u0430 \u0420\u043e\u0441\u0441\u0438\u0438, 1993. &#8211; 285 \u0441<\/li>\n<li>\u041d\u041e\u0412\u041e\u0421\u0418\u0411\u0418\u0420\u0421\u041a\u0418\u0419 \u0413\u041e\u0421\u0423\u0414\u0410\u0420\u0421\u0422\u0412\u0415\u041d\u041d\u042b\u0419 \u0410\u0413\u0420\u0410\u0420\u041d\u042b\u0419 \u0423\u041d\u0418\u0412\u0415\u0420\u0421\u0418\u0422\u0415\u0422<\/li>\n<li>\u0418\u041d\u0421\u0422\u0418\u0422\u0423\u0422 \u0417\u0410\u041e\u0427\u041d\u041e\u0413\u041e \u041e\u0411\u0420\u0410\u0417\u041e\u0412\u0410\u041d\u0418\u042f \u0418 \u041f\u041e\u0412\u042b\u0428\u0415\u041d\u0418\u042f \u041a\u0412\u0410\u041b\u0418\u0424\u0418\u041a\u0410\u0426\u0418 &#8220;\u0422\u0415\u0425\u041d\u041e\u041b\u0413\u042f \u041f\u0420\u041e\u0418\u0417\u0412\u0414\u0421\u0422\u0410 \u0411\u0418\u041e\u041b\u0413\u0418\u0418\u0427\u0415\u0421\u041a\u0418 \u0410\u041a\u0422\u0418\u0412\u041d\u0425 \u041f\u0420\u041e\u0414\u0423\u041a\u0422\u041e\u0412 \u041f\u0427\u0415\u041b\u0412\u041e\u0414\u0421\u0422\u0410&#8221; &#8211; \u0423\u0447\u0435\u0431\u043d\u043e\u0435 \u043f\u043e\u0441\u043e\u0431\u0438\u0435<\/li>\n<\/ol>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_divider _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; min_height=&#8221;706.6px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_heading title=&#8221;Preparati medicinali a base di veleno d&#039;api&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;Verdana||||||||&#8221; title_text_align=&#8221;center&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; text_shadow_style=&#8221;preset1&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_heading title=&#8221;Iliya Kanchev, Ph.D.&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; title_level=&#8221;h3&#8243; title_font=&#8221;Verdana||||||||&#8221; title_text_align=&#8221;center&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; max_height=&#8221;1000px&#8221; text_shadow_style=&#8221;preset1&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_heading][et_pb_text _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: center;\"><strong>Il veleno d&#8217;api \u00e8 utilizzato come ingrediente di molti farmaci in molti paesi del mondo.<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>APIFOR<\/h3>\n<p><span>Compresse contenenti 0,001 g di veleno d&#8217;api liofilizzato. Utilizzate per il trattamento di ionoforesi. Sciogli una compressa in 20 ml di acqua distillata e inserisci la soluzione nell&#8217;apparecchio per ionoforesi.  <\/span><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.beewhisper.com\/wp-content\/uploads\/2023\/09\/Apiphor-2-e1696065679189.jpg&#8221; title_text=&#8221;Apofora-2&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_divider _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; custom_padding=&#8221;2px|||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Apisarthron<\/h3>\n<p><span>Un preparato sotto forma di unguento o gel. Spalmalo o strofinalo sull&#8217;area interessata. <\/span><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.beewhisper.com\/wp-content\/uploads\/2023\/09\/Apisarthron.jpg&#8221; title_text=&#8221;Apisarthron&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_divider _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; custom_padding=&#8221;2px|||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Ungapiven  <\/h3>\n<p><span>Un unguento a base di veleno d&#8217;api. Strofinala per circa 5-10 minuti sull&#8217;area del dolore pi\u00f9 intenso. <\/span><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.beewhisper.com\/wp-content\/uploads\/2023\/09\/Ungapiven.jpg&#8221; title_text=&#8221;Ungapiven&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_divider _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; custom_padding=&#8221;1px|||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Venapiolinum  <\/h3>\n<p><span>Una preparazione a base di veleno d&#8217;api in olio vegetale. Utilizzato come antidolorifico e antinfiammatorio. Fiale da 1 ml. Venapiolinum 1 &#8211; soluzione sterile di veleno d&#8217;api (da 2-3 api) in 1 ml di olio vegetale. Venapiolinum 2 &#8211; una frazione volatile del veleno d&#8217;api appositamente preparata.    <\/span><\/p>\n<p>[\/et_pb_text][et_pb_divider _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; custom_padding=&#8221;1px|||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Virapin  <\/h3>\n<p><span>Fiale o unguenti. Viene utilizzato per il trattamento di reumatismi, poliartrite, vari tipi di nevralgie, radicolite, sciatica. <\/span><\/p>\n<p>[\/et_pb_text][et_pb_divider _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; custom_padding=&#8221;1px|||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>911 +<\/h3>\n<p>Un unguento a base di veleno d&#8217;api. Viene utilizzato come medicinale ausiliario nel trattamento di osteoartrite, radicolite e gotta. Riduce il dolore e l&#8217;edema e ripristina i tessuti cartilaginei. Ha effetti antinfiammatori e antireumatici. Migliora la mobilit\u00e0 articolare.    <\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.beewhisper.com\/wp-content\/uploads\/2023\/09\/911-C.jpg&#8221; title_text=&#8221;911-C&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_divider _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; custom_padding=&#8221;1px|||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Apitossina<\/h3>\n<p>Un preparato medicinale in fiale &#8211; una soluzione acquosa di veleno d&#8217;api. \u00c8 efficace per il trattamento delle malattie del sistema nervoso periferico e della radicolite. <\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.beewhisper.com\/wp-content\/uploads\/2023\/09\/apitoxin-e1696065795978.jpg&#8221; title_text=&#8221;apitossina&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_divider _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; custom_padding=&#8221;1px|||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Apireven<\/h3>\n<p><span data-preserver-spaces=\"true\">Un unguento contenente veleno d&#8217;api. Si usa per il trattamento di reumatismi cronici acuti, infiammazioni del nervo sciatico e lombaggini. CREMA AL VENOME D&#8217;API &#8211; 30ml SOLLIEVO VELOCE DOLORI MUSCOLARI E ARTICOLAZIONI MOLTO EFFICACE.    <\/span><strong><span data-preserver-spaces=\"true\">Ingredienti<\/span><\/strong><span data-preserver-spaces=\"true\">: Petrolato, lanolina, acqua, paraffinum liquidum, polisorbato 80, cera d&#8217;api, glicerina 26, estratto di capsico, canfora, metil nicotinato, estratto di propoli, tetraborato di sodio, veleno d&#8217;api. * Testato dermatologicamente <\/span><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.beewhisper.com\/wp-content\/uploads\/2023\/09\/apireven.jpg&#8221; title_text=&#8221;apireven&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_divider _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; custom_padding=&#8221;1px|||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1 class=\"product_title h1\">Venex, Unguento al veleno d&#8217;ape<\/h1>\n<p><span data-preserver-spaces=\"true\">L&#8217;unguento VeneX\u00ae al veleno d&#8217;ape \u00e8 realizzato con veleno d&#8217;ape.<\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Un preparato antinfiammatorio contenente veleno d&#8217;ape (Apis Venenum Purum) e oli naturali puri in una base idrosolubile (non grassa).<\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Le indicazioni presenti in letteratura sul veleno d&#8217;api includono:<\/span><\/p>\n<p><span data-preserver-spaces=\"true\">&#8211; Neurite cronica &#8211; artropatia degenerativa &#8211; disturbi funzionali di muscoli, legamenti e inserzioni tendinee &#8211; lombalgia &#8211; riscaldamento muscolare prima e durante l&#8217;attivit\u00e0 sportiva &#8211; mialgia &#8211; nevralgia &#8211; disturbi circolatori periferici &#8211; sciatica &#8211; poliartrite subcronica e cronica &#8211; lesioni sportive<\/span><\/p>\n<p class=\"ql-indent-1\"><strong><span data-preserver-spaces=\"true\">Principi attivi:  <\/span><\/strong><span data-preserver-spaces=\"true\">Apis Venenum Purum (veleno d&#8217;ape), metilnicotinato, Oleum sinapis volatile, Oleum Terebinthinae, olio di Piper nigrum e miscela proprietaria di oli essenziali puri. Ingredienti di origine naturale: 86,4%. <\/span><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.beewhisper.com\/wp-content\/uploads\/2023\/09\/venex-bee-venom-ointment-e1696065636558.png&#8221; title_text=&#8221;unguento venex-bee-venom&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;64%&#8221; max_width=&#8221;33%&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_divider _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; custom_padding=&#8221;1px|||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1 class=\"product_title h1\">Crema al veleno d&#8217;api Apixin<\/h1>\n<p><span data-preserver-spaces=\"true\">Apixin \u00e8 stato ideato per il trattamento di dolori articolari, muscolari, lombari, cervicali e alle spalle. Le persone possono identificare facilmente i loro sintomi con questo prodotto. Inoltre, contiene pi\u00f9 ingredienti naturali identici che sono approvati da EcoCert e accettati come conservanti sicuri.  <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Apixin Cream \u00e8 un preparato antinfiammatorio multicomponente contenente veleno d&#8217;ape di grado I (Apis Venenum Purum), oli essenziali puri e conservanti approvati da ECOCERT in una base idrosolubile (non grassa). L&#8217;elenco dettagliato degli ingredienti \u00e8 riportato sull&#8217;etichetta e nelle istruzioni per l&#8217;uso. Ingredienti di origine naturale o identici alla natura: 93,75%. Un tubo da 20 ml \u00e8 sufficiente per un trattamento di 7-10 giorni.   <\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Campo di applicazione:<\/span><\/p>\n<p><span data-preserver-spaces=\"true\">Terapia con veleno d&#8217;api, elettroforesi\/ionoforesi (elettrodo negativo), fisioterapia\/massoterapia, lesioni sportive, chiropratica, naturopatia, terapia atletica, industria del fitness, terapia Stiper, ultrasuonoforesi.<\/span><\/p>\n<p><strong><span data-preserver-spaces=\"true\">Ingredienti:<\/span><\/strong><\/p>\n<p class=\"ql-indent-1\"><span data-preserver-spaces=\"true\">Apis Venenum Purum (veleno d&#8217;ape), olio infuso di Arnica montana, Nicotinato di metile, Eugenolo, olio di Mentha piperita, olio di Eucalyptus globuli, Oleum sinapis volatile e Miscela proprietaria di oli essenziali puri. Acqua purificata, cloruro di sodio, fenossietanolo*, Caprylyl Glycol*, acido sorbico*, benzoato di sodio*, sorbato di potassio*, EDTA disodico in una base idrosolubile. Ingredienti di origine naturale o naturali identici: 93,75%.  <\/span><\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.beewhisper.com\/wp-content\/uploads\/2023\/09\/apixin-bee-venom-cream-e1696065560902.png&#8221; title_text=&#8221;apixin-ape-venom-crema&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; width=&#8221;64%&#8221; max_width=&#8221;33%&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_divider _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Effetto del veleno delle api sull&#8217;uomo L&#8217;effetto curativo del veleno d&#8217;api &nbsp; Effetto del veleno delle api sull&#8217;uomo L&#8217;effetto del veleno delle api sull&#8217;uomo \u00e8 altamente individuale. L&#8217;effetto tipico \u00e8 il seguente: Una reazione allergica si verifica nella maggior parte delle persone dopo una sola puntura. Questa reazione si verifica immediatamente o al massimo entro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-7971","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.beewhisper.com\/it\/wp-json\/wp\/v2\/pages\/7971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.beewhisper.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.beewhisper.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.beewhisper.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.beewhisper.com\/it\/wp-json\/wp\/v2\/comments?post=7971"}],"version-history":[{"count":1,"href":"https:\/\/www.beewhisper.com\/it\/wp-json\/wp\/v2\/pages\/7971\/revisions"}],"predecessor-version":[{"id":7995,"href":"https:\/\/www.beewhisper.com\/it\/wp-json\/wp\/v2\/pages\/7971\/revisions\/7995"}],"wp:attachment":[{"href":"https:\/\/www.beewhisper.com\/it\/wp-json\/wp\/v2\/media?parent=7971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}